{"id":3858,"date":"2022-12-31T22:31:53","date_gmt":"2022-12-31T20:31:53","guid":{"rendered":"https:\/\/aargauermuslime.ch\/de\/?p=3858"},"modified":"2022-12-31T22:43:56","modified_gmt":"2022-12-31T20:43:56","slug":"farbanschlag-auf-tuerkische-moschee-in-buchs-ag","status":"publish","type":"post","link":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/","title":{"rendered":"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG"},"content":{"rendered":"<p>In der Nacht auf den 31.12.2022 wurde auf die Mimar Sinan-Moschee in Buchs AG ein Farbanschlag ver\u00fcbt. Dabei entstand erheblicher Sachschaden. Es wurde Strafanzeige erstattet, die Polizei ermittelt.<\/p>\n<p>Wir als Verband Aargauer Muslime verurteilen diesen rassistischen Anschlag aufs Sch\u00e4rfste und rufen die Beh\u00f6rden dazu auf, alles zu unternehmen, um die Verantwortlichen zur Rechenschaft zu ziehen.<\/p>\n<p>Die Schmierereien deuten darauf hin, dass es sich um einen Racheakt f\u00fcr die Anschl\u00e4ge auf kurdische Einrichtungen in Paris letzte Woche handelt. Weder unsere Moschee in Buchs noch sonst irgend ein Mitglied von uns hat etwas damit zu tun. Wir verurteilen alle Anschl\u00e4ge und terroristische Akte und setzen weiterhin auf ein friedliches Zusammenleben aller Mitb\u00fcrgerinnen und Mitb\u00fcrger.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Nacht auf den 31.12.2022 wurde auf die Mimar Sinan-Moschee in Buchs AG ein Farbanschlag ver\u00fcbt. Dabei entstand erheblicher Sachschaden. Es wurde Strafanzeige erstattet, die Polizei ermittelt. Wir als [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-3858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-stellungnahmen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Farbanschlag auf t\u00fcrkische Moschee in Buchs AG - Verband Aargauer Muslime (VAM)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG - Verband Aargauer Muslime (VAM)\" \/>\n<meta property=\"og:description\" content=\"In der Nacht auf den 31.12.2022 wurde auf die Mimar Sinan-Moschee in Buchs AG ein Farbanschlag ver\u00fcbt. Dabei entstand erheblicher Sachschaden. Es wurde Strafanzeige erstattet, die Polizei ermittelt. Wir als [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/\" \/>\n<meta property=\"og:site_name\" content=\"Verband Aargauer Muslime (VAM)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/aargauermuslime\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-31T20:31:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-31T20:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2022\/12\/Kapo_Aargau_Emblem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Verwalter5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Verwalter5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/\"},\"author\":{\"name\":\"Verwalter5\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/person\\\/310e6c317a37722ccc1fb5815f4bb122\"},\"headline\":\"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG\",\"datePublished\":\"2022-12-31T20:31:53+00:00\",\"dateModified\":\"2022-12-31T20:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/\"},\"wordCount\":127,\"publisher\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Kapo_Aargau_Emblem.jpg\",\"articleSection\":[\"News\",\"Stellungnahmen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/\",\"name\":\"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG - Verband Aargauer Muslime (VAM)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Kapo_Aargau_Emblem.jpg\",\"datePublished\":\"2022-12-31T20:31:53+00:00\",\"dateModified\":\"2022-12-31T20:43:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Kapo_Aargau_Emblem.jpg\",\"contentUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Kapo_Aargau_Emblem.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/\",\"name\":\"Verband Aargauer Muslime (VAM)\",\"description\":\"Dachverband der muslimischen Institutionen im Aargau\",\"publisher\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#organization\",\"name\":\"Verband Aargauer Muslime\",\"alternateName\":\"VAM\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/VAM-Logo_web.jpg\",\"contentUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/VAM-Logo_web.jpg\",\"width\":800,\"height\":181,\"caption\":\"Verband Aargauer Muslime\"},\"image\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/aargauermuslime\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/person\\\/310e6c317a37722ccc1fb5815f4bb122\",\"name\":\"Verwalter5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g\",\"caption\":\"Verwalter5\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG - Verband Aargauer Muslime (VAM)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/","og_locale":"de_DE","og_type":"article","og_title":"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG - Verband Aargauer Muslime (VAM)","og_description":"In der Nacht auf den 31.12.2022 wurde auf die Mimar Sinan-Moschee in Buchs AG ein Farbanschlag ver\u00fcbt. Dabei entstand erheblicher Sachschaden. Es wurde Strafanzeige erstattet, die Polizei ermittelt. Wir als [&hellip;]","og_url":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/","og_site_name":"Verband Aargauer Muslime (VAM)","article_publisher":"https:\/\/www.facebook.com\/groups\/aargauermuslime","article_published_time":"2022-12-31T20:31:53+00:00","article_modified_time":"2022-12-31T20:43:56+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2022\/12\/Kapo_Aargau_Emblem.jpg","type":"image\/jpeg"}],"author":"Verwalter5","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Verwalter5","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#article","isPartOf":{"@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/"},"author":{"name":"Verwalter5","@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/person\/310e6c317a37722ccc1fb5815f4bb122"},"headline":"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG","datePublished":"2022-12-31T20:31:53+00:00","dateModified":"2022-12-31T20:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/"},"wordCount":127,"publisher":{"@id":"https:\/\/aargauermuslime.ch\/de\/#organization"},"image":{"@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#primaryimage"},"thumbnailUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2022\/12\/Kapo_Aargau_Emblem.jpg","articleSection":["News","Stellungnahmen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/","url":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/","name":"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG - Verband Aargauer Muslime (VAM)","isPartOf":{"@id":"https:\/\/aargauermuslime.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#primaryimage"},"image":{"@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#primaryimage"},"thumbnailUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2022\/12\/Kapo_Aargau_Emblem.jpg","datePublished":"2022-12-31T20:31:53+00:00","dateModified":"2022-12-31T20:43:56+00:00","breadcrumb":{"@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#primaryimage","url":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2022\/12\/Kapo_Aargau_Emblem.jpg","contentUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2022\/12\/Kapo_Aargau_Emblem.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/aargauermuslime.ch\/de\/farbanschlag-auf-tuerkische-moschee-in-buchs-ag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aargauermuslime.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Farbanschlag auf t\u00fcrkische Moschee in Buchs AG"}]},{"@type":"WebSite","@id":"https:\/\/aargauermuslime.ch\/de\/#website","url":"https:\/\/aargauermuslime.ch\/de\/","name":"Verband Aargauer Muslime (VAM)","description":"Dachverband der muslimischen Institutionen im Aargau","publisher":{"@id":"https:\/\/aargauermuslime.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aargauermuslime.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aargauermuslime.ch\/de\/#organization","name":"Verband Aargauer Muslime","alternateName":"VAM","url":"https:\/\/aargauermuslime.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2019\/07\/VAM-Logo_web.jpg","contentUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2019\/07\/VAM-Logo_web.jpg","width":800,"height":181,"caption":"Verband Aargauer Muslime"},"image":{"@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/aargauermuslime"]},{"@type":"Person","@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/person\/310e6c317a37722ccc1fb5815f4bb122","name":"Verwalter5","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g","caption":"Verwalter5"}}]}},"_links":{"self":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts\/3858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":4,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts\/3858\/revisions"}],"predecessor-version":[{"id":3863,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts\/3858\/revisions\/3863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/media\/3859"}],"wp:attachment":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/media?parent=3858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/categories?post=3858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/tags?post=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}