{"id":4456,"date":"2025-10-15T10:26:16","date_gmt":"2025-10-15T08:26:16","guid":{"rendered":"https:\/\/aargauermuslime.ch\/de\/?p=4456"},"modified":"2025-10-15T18:37:39","modified_gmt":"2025-10-15T16:37:39","slug":"wie-staerkt-dich-dein-glaube","status":"publish","type":"post","link":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/","title":{"rendered":"Wie st\u00e4rkt dich dein Glaube?"},"content":{"rendered":"<p>Angeh\u00f6rige verschiedener Religionsgemeinschaften laden im Rahmen der \u00ab<strong><a href=\"https:\/\/woche-der-religionen.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Woche der Religionen<\/a><\/strong>\u00bb ein, gemeinsam den Zusammenhang<br \/>\nzwischen Glaube und Gesundheit zu erkunden.<\/p>\n<div class=\"m-b-3\">\n<blockquote><p><strong>Datum und Zeit:<\/strong> 10.11.2025, 18:30 Uhr bis 20:30 Uhr<\/p>\n<p><strong>Ort:&nbsp;<\/strong>Reformierte Kirche Baden, Oelrainstrasse 21, 5400 Baden (keine Anmeldung erforderlich)<\/p>\n<p><strong>Weitere Infos:<\/strong> Siehe <a href=\"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Flyer_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.pdf\" target=\"_blank\" rel=\"noopener\">Flyer<\/a><\/p><\/blockquote>\n<\/div>\n<div class=\"m-b-3\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Angeh\u00f6rige verschiedener Religionsgemeinschaften laden im Rahmen der \u00abWoche der Religionen\u00bb ein, gemeinsam den Zusammenhang zwischen Glaube und Gesundheit zu erkunden. Datum und Zeit: 10.11.2025, 18:30 Uhr bis 20:30 Uhr Ort:&nbsp;Reformierte [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-4456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie st\u00e4rkt dich dein Glaube? - Verband Aargauer Muslime (VAM)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie st\u00e4rkt dich dein Glaube? - Verband Aargauer Muslime (VAM)\" \/>\n<meta property=\"og:description\" content=\"Angeh\u00f6rige verschiedener Religionsgemeinschaften laden im Rahmen der \u00abWoche der Religionen\u00bb ein, gemeinsam den Zusammenhang zwischen Glaube und Gesundheit zu erkunden. Datum und Zeit: 10.11.2025, 18:30 Uhr bis 20:30 Uhr Ort:&nbsp;Reformierte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/\" \/>\n<meta property=\"og:site_name\" content=\"Verband Aargauer Muslime (VAM)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/aargauermuslime\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T08:26:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T16:37:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"853\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Verwalter5\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Verwalter5\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/\"},\"author\":{\"name\":\"Verwalter5\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/person\\\/310e6c317a37722ccc1fb5815f4bb122\"},\"headline\":\"Wie st\u00e4rkt dich dein Glaube?\",\"datePublished\":\"2025-10-15T08:26:16+00:00\",\"dateModified\":\"2025-10-15T16:37:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png\",\"articleSection\":[\"News\",\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/\",\"name\":\"Wie st\u00e4rkt dich dein Glaube? - Verband Aargauer Muslime (VAM)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png\",\"datePublished\":\"2025-10-15T08:26:16+00:00\",\"dateModified\":\"2025-10-15T16:37:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png\",\"contentUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png\",\"width\":853,\"height\":604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wie-staerkt-dich-dein-glaube\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie st\u00e4rkt dich dein Glaube?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/\",\"name\":\"Verband Aargauer Muslime (VAM)\",\"description\":\"Dachverband der muslimischen Institutionen im Aargau\",\"publisher\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#organization\",\"name\":\"Verband Aargauer Muslime\",\"alternateName\":\"VAM\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/VAM-Logo_web.jpg\",\"contentUrl\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/VAM-Logo_web.jpg\",\"width\":800,\"height\":181,\"caption\":\"Verband Aargauer Muslime\"},\"image\":{\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/aargauermuslime\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aargauermuslime.ch\\\/de\\\/#\\\/schema\\\/person\\\/310e6c317a37722ccc1fb5815f4bb122\",\"name\":\"Verwalter5\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g\",\"caption\":\"Verwalter5\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie st\u00e4rkt dich dein Glaube? - Verband Aargauer Muslime (VAM)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/","og_locale":"de_DE","og_type":"article","og_title":"Wie st\u00e4rkt dich dein Glaube? - Verband Aargauer Muslime (VAM)","og_description":"Angeh\u00f6rige verschiedener Religionsgemeinschaften laden im Rahmen der \u00abWoche der Religionen\u00bb ein, gemeinsam den Zusammenhang zwischen Glaube und Gesundheit zu erkunden. Datum und Zeit: 10.11.2025, 18:30 Uhr bis 20:30 Uhr Ort:&nbsp;Reformierte [&hellip;]","og_url":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/","og_site_name":"Verband Aargauer Muslime (VAM)","article_publisher":"https:\/\/www.facebook.com\/groups\/aargauermuslime","article_published_time":"2025-10-15T08:26:16+00:00","article_modified_time":"2025-10-15T16:37:39+00:00","og_image":[{"width":853,"height":604,"url":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png","type":"image\/png"}],"author":"Verwalter5","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Verwalter5","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#article","isPartOf":{"@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/"},"author":{"name":"Verwalter5","@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/person\/310e6c317a37722ccc1fb5815f4bb122"},"headline":"Wie st\u00e4rkt dich dein Glaube?","datePublished":"2025-10-15T08:26:16+00:00","dateModified":"2025-10-15T16:37:39+00:00","mainEntityOfPage":{"@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/"},"wordCount":48,"publisher":{"@id":"https:\/\/aargauermuslime.ch\/de\/#organization"},"image":{"@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#primaryimage"},"thumbnailUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png","articleSection":["News","Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/","url":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/","name":"Wie st\u00e4rkt dich dein Glaube? - Verband Aargauer Muslime (VAM)","isPartOf":{"@id":"https:\/\/aargauermuslime.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#primaryimage"},"image":{"@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#primaryimage"},"thumbnailUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png","datePublished":"2025-10-15T08:26:16+00:00","dateModified":"2025-10-15T16:37:39+00:00","breadcrumb":{"@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#primaryimage","url":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png","contentUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2025\/10\/Banner_Wie-staerkt-dich-dein-Glaube_WdR_Baden_2025-10-15.png","width":853,"height":604},{"@type":"BreadcrumbList","@id":"https:\/\/aargauermuslime.ch\/de\/wie-staerkt-dich-dein-glaube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aargauermuslime.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Wie st\u00e4rkt dich dein Glaube?"}]},{"@type":"WebSite","@id":"https:\/\/aargauermuslime.ch\/de\/#website","url":"https:\/\/aargauermuslime.ch\/de\/","name":"Verband Aargauer Muslime (VAM)","description":"Dachverband der muslimischen Institutionen im Aargau","publisher":{"@id":"https:\/\/aargauermuslime.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aargauermuslime.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aargauermuslime.ch\/de\/#organization","name":"Verband Aargauer Muslime","alternateName":"VAM","url":"https:\/\/aargauermuslime.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2019\/07\/VAM-Logo_web.jpg","contentUrl":"https:\/\/aargauermuslime.ch\/de\/wp-content\/uploads\/2019\/07\/VAM-Logo_web.jpg","width":800,"height":181,"caption":"Verband Aargauer Muslime"},"image":{"@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/aargauermuslime"]},{"@type":"Person","@id":"https:\/\/aargauermuslime.ch\/de\/#\/schema\/person\/310e6c317a37722ccc1fb5815f4bb122","name":"Verwalter5","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/65ee8be834871e73d854ad00dfc4031afc2b5c926eac730b926dfe8fee7021c0?s=96&d=mm&r=g","caption":"Verwalter5"}}]}},"_links":{"self":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts\/4456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/comments?post=4456"}],"version-history":[{"count":3,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts\/4456\/revisions"}],"predecessor-version":[{"id":4463,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/posts\/4456\/revisions\/4463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/media\/4458"}],"wp:attachment":[{"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/media?parent=4456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/categories?post=4456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aargauermuslime.ch\/de\/wp-json\/wp\/v2\/tags?post=4456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}